{"id":13003,"count":30,"description":"","link":"https:\/\/craftygenesindonesia.com\/pt-br\/categoria-produto\/padroes-de-croche-3d\/","name":"Padr\u00f5es de croch\u00ea 3D","slug":"padroes-de-croche-3d","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de Padr\u00f5es de croch\u00ea 3D - Craftygenesindonesia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/craftygenesindonesia.com\/pt-br\/categoria-produto\/padroes-de-croche-3d\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Padr\u00f5es de croch\u00ea 3D - Craftygenesindonesia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/craftygenesindonesia.com\/pt-br\/categoria-produto\/padroes-de-croche-3d\/\" \/>\n<meta property=\"og:site_name\" content=\"Craftygenesindonesia\" \/>\n<meta property=\"og:image\" content=\"https:\/\/craftygenesindonesia.com\/wp-content\/uploads\/2025\/01\/Koekoeksklok.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/pt-br\\\/categoria-produto\\\/padroes-de-croche-3d\\\/\",\"url\":\"https:\\\/\\\/craftygenesindonesia.com\\\/pt-br\\\/categoria-produto\\\/padroes-de-croche-3d\\\/\",\"name\":\"Arquivo de Padr\u00f5es de croch\u00ea 3D - Craftygenesindonesia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/pt-br\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/pt-br\\\/categoria-produto\\\/padroes-de-croche-3d\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/pt-br\\\/categoria-produto\\\/padroes-de-croche-3d\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/craftygenesindonesia.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Padr\u00f5es de croch\u00ea 3D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/craftygenesindonesia.com\\\/pt-br\\\/\",\"name\":\"Craftygenesindonesia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/craftygenesindonesia.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/pt-br\\\/#organization\",\"name\":\"Craftygenesindonesia\",\"url\":\"https:\\\/\\\/craftygenesindonesia.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/craftygenesindonesia.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cropped-Copy-of-Craftygenesindonesia.jpg\",\"contentUrl\":\"https:\\\/\\\/craftygenesindonesia.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cropped-Copy-of-Craftygenesindonesia.jpg\",\"width\":180,\"height\":60,\"caption\":\"Craftygenesindonesia\"},\"image\":{\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de Padr\u00f5es de croch\u00ea 3D - Craftygenesindonesia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/craftygenesindonesia.com\/pt-br\/categoria-produto\/padroes-de-croche-3d\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de Padr\u00f5es de croch\u00ea 3D - Craftygenesindonesia","og_url":"https:\/\/craftygenesindonesia.com\/pt-br\/categoria-produto\/padroes-de-croche-3d\/","og_site_name":"Craftygenesindonesia","og_image":[{"width":1080,"height":1080,"url":"https:\/\/craftygenesindonesia.com\/wp-content\/uploads\/2025\/01\/Koekoeksklok.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/craftygenesindonesia.com\/pt-br\/categoria-produto\/padroes-de-croche-3d\/","url":"https:\/\/craftygenesindonesia.com\/pt-br\/categoria-produto\/padroes-de-croche-3d\/","name":"Arquivo de Padr\u00f5es de croch\u00ea 3D - Craftygenesindonesia","isPartOf":{"@id":"https:\/\/craftygenesindonesia.com\/pt-br\/#website"},"breadcrumb":{"@id":"https:\/\/craftygenesindonesia.com\/pt-br\/categoria-produto\/padroes-de-croche-3d\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/craftygenesindonesia.com\/pt-br\/categoria-produto\/padroes-de-croche-3d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/craftygenesindonesia.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Padr\u00f5es de croch\u00ea 3D"}]},{"@type":"WebSite","@id":"https:\/\/craftygenesindonesia.com\/pt-br\/#website","url":"https:\/\/craftygenesindonesia.com\/pt-br\/","name":"Craftygenesindonesia","description":"","publisher":{"@id":"https:\/\/craftygenesindonesia.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/craftygenesindonesia.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/craftygenesindonesia.com\/pt-br\/#organization","name":"Craftygenesindonesia","url":"https:\/\/craftygenesindonesia.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/craftygenesindonesia.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/craftygenesindonesia.com\/wp-content\/uploads\/2025\/11\/cropped-Copy-of-Craftygenesindonesia.jpg","contentUrl":"https:\/\/craftygenesindonesia.com\/wp-content\/uploads\/2025\/11\/cropped-Copy-of-Craftygenesindonesia.jpg","width":180,"height":60,"caption":"Craftygenesindonesia"},"image":{"@id":"https:\/\/craftygenesindonesia.com\/pt-br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/craftygenesindonesia.com\/pt-br\/wp-json\/wp\/v2\/product_cat\/13003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/craftygenesindonesia.com\/pt-br\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/craftygenesindonesia.com\/pt-br\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/craftygenesindonesia.com\/pt-br\/wp-json\/wp\/v2\/product?product_cat=13003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}