{"id":406,"count":20,"description":"","link":"https:\/\/craftygenesindonesia.com\/nl\/product-categorie\/dieren-haakpatronen\/","name":"Dieren haakpatronen","slug":"dieren-haakpatronen","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":5,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dieren haakpatronen - Craftygenesindonesia<\/title>\n<meta name=\"description\" content=\"Bestel hier de Craftygenesindonesia dieren haakpatronen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/craftygenesindonesia.com\/nl\/product-categorie\/dieren-haakpatronen\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dieren haakpatronen - Craftygenesindonesia\" \/>\n<meta property=\"og:description\" content=\"Bestel hier de Craftygenesindonesia dieren haakpatronen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/craftygenesindonesia.com\/nl\/product-categorie\/dieren-haakpatronen\/\" \/>\n<meta property=\"og:site_name\" content=\"Craftygenesindonesia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/nl\\\/product-categorie\\\/dieren-haakpatronen\\\/\",\"url\":\"https:\\\/\\\/craftygenesindonesia.com\\\/nl\\\/product-categorie\\\/dieren-haakpatronen\\\/\",\"name\":\"Dieren haakpatronen - Craftygenesindonesia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/nl\\\/#website\"},\"description\":\"Bestel hier de Craftygenesindonesia dieren haakpatronen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/nl\\\/product-categorie\\\/dieren-haakpatronen\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/nl\\\/product-categorie\\\/dieren-haakpatronen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/craftygenesindonesia.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dieren haakpatronen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/craftygenesindonesia.com\\\/nl\\\/\",\"name\":\"Craftygenesindonesia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/craftygenesindonesia.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/nl\\\/#organization\",\"name\":\"Craftygenesindonesia\",\"url\":\"https:\\\/\\\/craftygenesindonesia.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/craftygenesindonesia.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cropped-Copy-of-Craftygenesindonesia.jpg\",\"contentUrl\":\"https:\\\/\\\/craftygenesindonesia.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cropped-Copy-of-Craftygenesindonesia.jpg\",\"width\":180,\"height\":60,\"caption\":\"Craftygenesindonesia\"},\"image\":{\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dieren haakpatronen - Craftygenesindonesia","description":"Bestel hier de Craftygenesindonesia dieren haakpatronen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/craftygenesindonesia.com\/nl\/product-categorie\/dieren-haakpatronen\/","og_locale":"nl_NL","og_type":"article","og_title":"Dieren haakpatronen - Craftygenesindonesia","og_description":"Bestel hier de Craftygenesindonesia dieren haakpatronen.","og_url":"https:\/\/craftygenesindonesia.com\/nl\/product-categorie\/dieren-haakpatronen\/","og_site_name":"Craftygenesindonesia","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/craftygenesindonesia.com\/nl\/product-categorie\/dieren-haakpatronen\/","url":"https:\/\/craftygenesindonesia.com\/nl\/product-categorie\/dieren-haakpatronen\/","name":"Dieren haakpatronen - Craftygenesindonesia","isPartOf":{"@id":"https:\/\/craftygenesindonesia.com\/nl\/#website"},"description":"Bestel hier de Craftygenesindonesia dieren haakpatronen.","breadcrumb":{"@id":"https:\/\/craftygenesindonesia.com\/nl\/product-categorie\/dieren-haakpatronen\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/craftygenesindonesia.com\/nl\/product-categorie\/dieren-haakpatronen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/craftygenesindonesia.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Dieren haakpatronen"}]},{"@type":"WebSite","@id":"https:\/\/craftygenesindonesia.com\/nl\/#website","url":"https:\/\/craftygenesindonesia.com\/nl\/","name":"Craftygenesindonesia","description":"","publisher":{"@id":"https:\/\/craftygenesindonesia.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/craftygenesindonesia.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/craftygenesindonesia.com\/nl\/#organization","name":"Craftygenesindonesia","url":"https:\/\/craftygenesindonesia.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/craftygenesindonesia.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/craftygenesindonesia.com\/wp-content\/uploads\/2025\/11\/cropped-Copy-of-Craftygenesindonesia.jpg","contentUrl":"https:\/\/craftygenesindonesia.com\/wp-content\/uploads\/2025\/11\/cropped-Copy-of-Craftygenesindonesia.jpg","width":180,"height":60,"caption":"Craftygenesindonesia"},"image":{"@id":"https:\/\/craftygenesindonesia.com\/nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/craftygenesindonesia.com\/nl\/wp-json\/wp\/v2\/product_cat\/406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/craftygenesindonesia.com\/nl\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/craftygenesindonesia.com\/nl\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/craftygenesindonesia.com\/nl\/wp-json\/wp\/v2\/product?product_cat=406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}