{"id":11734,"count":1,"description":"","link":"https:\/\/craftygenesindonesia.com\/fr\/categorie-produit\/modeles-de-tricot-de-noel\/","name":"Mod\u00e8les de tricot de No\u00ebl","slug":"modeles-de-tricot-de-noel","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":10,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Mod\u00e8les de tricot de No\u00ebl - Craftygenesindonesia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/craftygenesindonesia.com\/fr\/categorie-produit\/modeles-de-tricot-de-noel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Mod\u00e8les de tricot de No\u00ebl - Craftygenesindonesia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/craftygenesindonesia.com\/fr\/categorie-produit\/modeles-de-tricot-de-noel\/\" \/>\n<meta property=\"og:site_name\" content=\"Craftygenesindonesia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/fr\\\/categorie-produit\\\/modeles-de-tricot-de-noel\\\/\",\"url\":\"https:\\\/\\\/craftygenesindonesia.com\\\/fr\\\/categorie-produit\\\/modeles-de-tricot-de-noel\\\/\",\"name\":\"Archives des Mod\u00e8les de tricot de No\u00ebl - Craftygenesindonesia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/fr\\\/categorie-produit\\\/modeles-de-tricot-de-noel\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/fr\\\/categorie-produit\\\/modeles-de-tricot-de-noel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/craftygenesindonesia.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mod\u00e8les de tricot de No\u00ebl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/craftygenesindonesia.com\\\/fr\\\/\",\"name\":\"Craftygenesindonesia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/craftygenesindonesia.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/fr\\\/#organization\",\"name\":\"Craftygenesindonesia\",\"url\":\"https:\\\/\\\/craftygenesindonesia.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/craftygenesindonesia.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cropped-Copy-of-Craftygenesindonesia.jpg\",\"contentUrl\":\"https:\\\/\\\/craftygenesindonesia.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cropped-Copy-of-Craftygenesindonesia.jpg\",\"width\":180,\"height\":60,\"caption\":\"Craftygenesindonesia\"},\"image\":{\"@id\":\"https:\\\/\\\/craftygenesindonesia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Mod\u00e8les de tricot de No\u00ebl - Craftygenesindonesia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/craftygenesindonesia.com\/fr\/categorie-produit\/modeles-de-tricot-de-noel\/","og_locale":"fr_FR","og_type":"article","og_title":"Archives des Mod\u00e8les de tricot de No\u00ebl - Craftygenesindonesia","og_url":"https:\/\/craftygenesindonesia.com\/fr\/categorie-produit\/modeles-de-tricot-de-noel\/","og_site_name":"Craftygenesindonesia","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/craftygenesindonesia.com\/fr\/categorie-produit\/modeles-de-tricot-de-noel\/","url":"https:\/\/craftygenesindonesia.com\/fr\/categorie-produit\/modeles-de-tricot-de-noel\/","name":"Archives des Mod\u00e8les de tricot de No\u00ebl - Craftygenesindonesia","isPartOf":{"@id":"https:\/\/craftygenesindonesia.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/craftygenesindonesia.com\/fr\/categorie-produit\/modeles-de-tricot-de-noel\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/craftygenesindonesia.com\/fr\/categorie-produit\/modeles-de-tricot-de-noel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/craftygenesindonesia.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Mod\u00e8les de tricot de No\u00ebl"}]},{"@type":"WebSite","@id":"https:\/\/craftygenesindonesia.com\/fr\/#website","url":"https:\/\/craftygenesindonesia.com\/fr\/","name":"Craftygenesindonesia","description":"","publisher":{"@id":"https:\/\/craftygenesindonesia.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/craftygenesindonesia.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/craftygenesindonesia.com\/fr\/#organization","name":"Craftygenesindonesia","url":"https:\/\/craftygenesindonesia.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/craftygenesindonesia.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/craftygenesindonesia.com\/wp-content\/uploads\/2025\/11\/cropped-Copy-of-Craftygenesindonesia.jpg","contentUrl":"https:\/\/craftygenesindonesia.com\/wp-content\/uploads\/2025\/11\/cropped-Copy-of-Craftygenesindonesia.jpg","width":180,"height":60,"caption":"Craftygenesindonesia"},"image":{"@id":"https:\/\/craftygenesindonesia.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/craftygenesindonesia.com\/fr\/wp-json\/wp\/v2\/product_cat\/11734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/craftygenesindonesia.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/craftygenesindonesia.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/craftygenesindonesia.com\/fr\/wp-json\/wp\/v2\/product?product_cat=11734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}